{"id":936,"date":"2022-09-01T10:51:23","date_gmt":"2022-09-01T10:51:23","guid":{"rendered":"https:\/\/embutidoslalinense.com\/blog\/?p=936"},"modified":"2023-01-16T11:12:54","modified_gmt":"2023-01-16T11:12:54","slug":"risotto-de-chorizo-criollo","status":"publish","type":"post","link":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/","title":{"rendered":"Risotto de chorizo criollo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vale para todo. Como acompa\u00f1amiento y como plato principal. El arroz no solo es el cereal m\u00e1s consumido en el mundo, sino que es el alimento m\u00e1s vers\u00e1til de nuestra cocina.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Espa\u00f1a ya es un t\u00f3pico eso de asociar el arroz con la paella. Al igual que lo es pensar en el criollo para una buena barbacoa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y si algo nos simboliza a Embutidos Lalinense es la apuesta por lo tradicional, pero nos apasiona versionar recetas y descubrirte <strong>platos deliciosos con los que sorprender a tu familia y amigos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-1024x843.jpg\" alt=\"\" class=\"wp-image-995\" width=\"512\" height=\"422\" srcset=\"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-1024x843.jpg 1024w, https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-300x247.jpg 300w, https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-768x632.jpg 768w, https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1.jpg 1498w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Risotto de chorizo criollo<\/figcaption><\/figure>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#2a749f\"><br><strong>\u00bfQu\u00e9 necesitas?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed que ah\u00ed va nuestra propuesta de hoy: <strong>receta f\u00e1cil de risotto con criollos<\/strong>. Te sorprender\u00e1 lo sencillo que es disfrutar de este singular plato italiano con el sabor de los mejores productos de nuestra marca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1 bandeja de <a href=\"https:\/\/www.embutidoslalinense.com\/tienda\/frescos\/chorizo-criollo-fresco\">chorizo criollo fresco <\/a> de Embutidos Lalinense<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1 paquete de arroz arborio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1 litro de caldo de verduras<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1 cu\u00f1a de queso <em>parmigiano reggiano<\/em><\/p>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#2a749f\"><strong>Vayamos por partes\u2026<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El risotto de chapi\u00f1ones es una de las m\u00edticas recetas de arroz italianas con las que todos nos chupamos los dedos. Un arroz cremoso y sabroso que no deja indiferente a nadie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque su preparaci\u00f3n es muy diferente a cualquier otro plato de arroz, basta con elegir el producto adecuado y seguir unos sencillos pasos para preparar una incre\u00edble <strong>receta de risotto de chorizo criollo f\u00e1cil<\/strong>.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Haz un corte<\/strong> a la piel de los criollos y ret\u00edrala. Corta el <strong>criollo en trocitos.<\/strong><\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">2.  <strong style=\"font-size: revert; color: initial;\">Calienta el caldo<\/strong><span style=\"font-size: revert; color: initial;\"> de verduras y d\u00e9jalo que mantenga la temperatura a fuego bajo.<\/span> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. <span style=\"font-size: revert; color: initial;\">Pon una cucharada generosa de <\/span><strong style=\"font-size: revert; color: initial;\">mantequilla a calentar<\/strong><span style=\"font-size: revert; color: initial;\"> en una olla amplia. <\/span><strong style=\"font-size: revert; color: initial;\">Incorpora los criollos y saltea<\/strong><span style=\"font-size: revert; color: initial;\"> a fuego medio-alto hasta que est\u00e9n sueltos.<\/span> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.  <strong style=\"font-size: revert; color: initial;\">A\u00f1ade el arroz<\/strong><span style=\"font-size: revert; color: initial;\"> y dale un par de vueltas para que se mezcle con los criollos.<\/span> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. <strong>Echa 3 cucharones de caldo<\/strong> de verduras sobre el arroz y <strong>remueve<\/strong> constantemente a fuego medio-bajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. Antes de que el arroz se seque por completo, <strong>a\u00f1ade otra cucharada de caldo<\/strong> de verduras caliente <strong>y sigue removiendo<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. Cada vez que el arroz empieza a secarse, a\u00f1ade una cucharada y remueve. Repite el proceso hasta que quede s\u00f3lo una cucharada de caldo. En unos <strong>15-20 minutos<\/strong> deber\u00edas tener el risotto a punto para el \u00faltimo paso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8. <strong>Ralla el queso <\/strong>sobre el arroz y ve removiendo seg\u00fan lo incorporas. Aseg\u00farate de tener el fuego bajo para que no se queme. (Puedes hacerlo m\u00e1s sencillo si compras el queso rallado o en polvo).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9. A\u00f1ade una \u00faltima cucharada generosa de caldo para hidratar el queso en la mezcla y sirve inmediatamente.&nbsp;<\/p>\n\n\n\n<h2 class=\"has-vivid-red-color has-text-color wp-block-heading\"><strong>El truco del almendruco:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La receta tradicional de risotto incorpora una cebolleta picada salteada como primer paso, pero no es condici\u00f3n <em>sine qua non<\/em> para preparar un <strong>delicioso risotto de criollos<\/strong>. As\u00ed que a\u00f1\u00e1dela o no a tu gusto en la elaboraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La particularidad del risotto es ese resultado cremoso. Para conseguir disfrutarlo es necesario respetar dos m\u00e1ximas:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Hay que <strong>remover el arroz constantemente<\/strong> mientras se prepara el risotto.<\/li><li>Los comensales deben <strong>esperar por el risotto<\/strong>, no el risotto por los comensales. De lo contrario, comer\u00e9is una masa compacta de arroz. Incre\u00edblemente sabrosa, eso s\u00ed, pero compacta.&nbsp;<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima cucharada de caldo no es obligatoria, pero te <strong>permitir\u00e1 mantener el arroz m\u00e1s suelto<\/strong> hasta servirlo y ayudar\u00e1 a hidratar el queso para que suelte todo su sabor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vale para todo. Como acompa\u00f1amiento y como plato principal. El arroz no solo es el cereal m\u00e1s consumido en el mundo, sino que es el alimento m\u00e1s vers\u00e1til de nuestra cocina.&nbsp; En Espa\u00f1a ya es un t\u00f3pico eso de asociar el arroz con la paella. Al igual que lo es pensar en el criollo para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[88,17,48,166,178,177],"class_list":["post-936","post","type-post","status-publish","format-standard","hentry","category-recetas","tag-chorizo-criollo","tag-embutidos-lalinense","tag-lalinense","tag-recetas-2022","tag-recetas-de-calendario","tag-risotto-de-criollo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risotto de chorizo criollo - Embutidos Lalinense<\/title>\n<meta name=\"description\" content=\"El arroz es a la paella lo que el criollo a la barbacoa, por eso hoy nos atrevemos con una receta tan poco tradicional como suculenta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risotto de chorizo criollo - Embutidos Lalinense\" \/>\n<meta property=\"og:description\" content=\"El arroz es a la paella lo que el criollo a la barbacoa, por eso hoy nos atrevemos con una receta tan poco tradicional como suculenta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/\" \/>\n<meta property=\"og:site_name\" content=\"Embutidos Lalinense\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/embutidos.lalinense\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-01T10:51:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-16T11:12:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-1024x843.jpg\" \/>\n<meta name=\"author\" content=\"Embutidos Lalinense\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Embutidos Lalinense\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/\"},\"author\":{\"name\":\"Embutidos Lalinense\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#\\\/schema\\\/person\\\/147b4407f4d12f239cb03a5fa82fd9c4\"},\"headline\":\"Risotto de chorizo criollo\",\"datePublished\":\"2022-09-01T10:51:23+00:00\",\"dateModified\":\"2023-01-16T11:12:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/\"},\"wordCount\":586,\"publisher\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/risotto-1-1024x843.jpg\",\"keywords\":[\"chorizo criollo\",\"embutidos lalinense\",\"lalinense\",\"recetas 2022\",\"recetas de calendario\",\"risotto de criollo\"],\"articleSection\":[\"RECETAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/\",\"url\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/\",\"name\":\"Risotto de chorizo criollo - Embutidos Lalinense\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/risotto-1-1024x843.jpg\",\"datePublished\":\"2022-09-01T10:51:23+00:00\",\"dateModified\":\"2023-01-16T11:12:54+00:00\",\"description\":\"El arroz es a la paella lo que el criollo a la barbacoa, por eso hoy nos atrevemos con una receta tan poco tradicional como suculenta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/risotto-1.jpg\",\"contentUrl\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/risotto-1.jpg\",\"width\":1498,\"height\":1233},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/risotto-de-chorizo-criollo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Risotto de chorizo criollo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/\",\"name\":\"Embutidos Lalinense\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#organization\",\"name\":\"Embutidos Lalinense\",\"url\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/0001.jpg\",\"contentUrl\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/0001.jpg\",\"width\":1494,\"height\":557,\"caption\":\"Embutidos Lalinense\"},\"image\":{\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/embutidos.lalinense\\\/\",\"https:\\\/\\\/www.instagram.com\\\/embutidoslalinense\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCij-z5cQeLRTChmF69LeJjw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/#\\\/schema\\\/person\\\/147b4407f4d12f239cb03a5fa82fd9c4\",\"name\":\"Embutidos Lalinense\",\"url\":\"https:\\\/\\\/embutidoslalinense.com\\\/blog\\\/author\\\/embutidos-lalinense\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risotto de chorizo criollo - Embutidos Lalinense","description":"El arroz es a la paella lo que el criollo a la barbacoa, por eso hoy nos atrevemos con una receta tan poco tradicional como suculenta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/","og_locale":"es_ES","og_type":"article","og_title":"Risotto de chorizo criollo - Embutidos Lalinense","og_description":"El arroz es a la paella lo que el criollo a la barbacoa, por eso hoy nos atrevemos con una receta tan poco tradicional como suculenta.","og_url":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/","og_site_name":"Embutidos Lalinense","article_publisher":"https:\/\/www.facebook.com\/embutidos.lalinense\/","article_published_time":"2022-09-01T10:51:23+00:00","article_modified_time":"2023-01-16T11:12:54+00:00","og_image":[{"url":"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-1024x843.jpg","type":"","width":"","height":""}],"author":"Embutidos Lalinense","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Embutidos Lalinense","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/#article","isPartOf":{"@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/"},"author":{"name":"Embutidos Lalinense","@id":"https:\/\/embutidoslalinense.com\/blog\/#\/schema\/person\/147b4407f4d12f239cb03a5fa82fd9c4"},"headline":"Risotto de chorizo criollo","datePublished":"2022-09-01T10:51:23+00:00","dateModified":"2023-01-16T11:12:54+00:00","mainEntityOfPage":{"@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/"},"wordCount":586,"publisher":{"@id":"https:\/\/embutidoslalinense.com\/blog\/#organization"},"image":{"@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/#primaryimage"},"thumbnailUrl":"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-1024x843.jpg","keywords":["chorizo criollo","embutidos lalinense","lalinense","recetas 2022","recetas de calendario","risotto de criollo"],"articleSection":["RECETAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/","url":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/","name":"Risotto de chorizo criollo - Embutidos Lalinense","isPartOf":{"@id":"https:\/\/embutidoslalinense.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/#primaryimage"},"image":{"@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/#primaryimage"},"thumbnailUrl":"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1-1024x843.jpg","datePublished":"2022-09-01T10:51:23+00:00","dateModified":"2023-01-16T11:12:54+00:00","description":"El arroz es a la paella lo que el criollo a la barbacoa, por eso hoy nos atrevemos con una receta tan poco tradicional como suculenta.","breadcrumb":{"@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/#primaryimage","url":"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1.jpg","contentUrl":"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2021\/10\/risotto-1.jpg","width":1498,"height":1233},{"@type":"BreadcrumbList","@id":"https:\/\/embutidoslalinense.com\/blog\/risotto-de-chorizo-criollo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/embutidoslalinense.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Risotto de chorizo criollo"}]},{"@type":"WebSite","@id":"https:\/\/embutidoslalinense.com\/blog\/#website","url":"https:\/\/embutidoslalinense.com\/blog\/","name":"Embutidos Lalinense","description":"","publisher":{"@id":"https:\/\/embutidoslalinense.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/embutidoslalinense.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/embutidoslalinense.com\/blog\/#organization","name":"Embutidos Lalinense","url":"https:\/\/embutidoslalinense.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/embutidoslalinense.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2020\/04\/0001.jpg","contentUrl":"https:\/\/embutidoslalinense.com\/blog\/wp-content\/uploads\/2020\/04\/0001.jpg","width":1494,"height":557,"caption":"Embutidos Lalinense"},"image":{"@id":"https:\/\/embutidoslalinense.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/embutidos.lalinense\/","https:\/\/www.instagram.com\/embutidoslalinense\/","https:\/\/www.youtube.com\/channel\/UCij-z5cQeLRTChmF69LeJjw"]},{"@type":"Person","@id":"https:\/\/embutidoslalinense.com\/blog\/#\/schema\/person\/147b4407f4d12f239cb03a5fa82fd9c4","name":"Embutidos Lalinense","url":"https:\/\/embutidoslalinense.com\/blog\/author\/embutidos-lalinense\/"}]}},"_links":{"self":[{"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/posts\/936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/comments?post=936"}],"version-history":[{"count":4,"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/posts\/936\/revisions"}],"predecessor-version":[{"id":997,"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/posts\/936\/revisions\/997"}],"wp:attachment":[{"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/media?parent=936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/categories?post=936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/embutidoslalinense.com\/blog\/wp-json\/wp\/v2\/tags?post=936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}